{"id":6955,"date":"2023-02-08T08:04:00","date_gmt":"2023-02-08T14:04:00","guid":{"rendered":"https:\/\/mezcalent.com\/news\/?p=6955"},"modified":"2023-02-08T09:14:12","modified_gmt":"2023-02-08T15:14:12","slug":"video-christian-de-la-campa-iba-a-entrar-al-fbi","status":"publish","type":"post","link":"https:\/\/mezcalent.com\/news\/video-christian-de-la-campa-iba-a-entrar-al-fbi-6955.html","title":{"rendered":"VIDEO: Christian de la Campa iba a entrar al FBI"},"content":{"rendered":"\n<p>08 FEB (MEX).- Christian de la Campa actualmente participa en la telenovela \u00abCabo\u00bb (Univision), al aire en Estados Unidos, pero la oportunidad de ser actor lleg\u00f3 en medio de proyectos con los que buscaba ser parte del FBI, pues estuvo enlistado en la Fuerza A\u00e9rea Norteamericana.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00abEn la Fuerza A\u00e9rea fui mec\u00e1nico de aviones y termin\u00e9 dos carreras estando all\u00e1; termin\u00e9 Criminolog\u00eda y Mec\u00e1nica de Aviaci\u00f3n.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00abFaltaban como tres o cuatro meses para terminar mi carrera de Criminolog\u00eda. Mi plan era terminar esa carrera e irme al FBI, iba a regresarme a Texas, iba a hacer el ex\u00e1men para ver si pod\u00eda entrar al FBI, quer\u00eda entrar a la secci\u00f3n de antiterrorismo\u00bb.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>El tapat\u00edo recuerda cu\u00e1l fue el principal reto, al cambiar sus planes en el ej\u00e9rcito y probar suerte en la actuaci\u00f3n.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00abEntro a la actuaci\u00f3n y de repente descubres que vienes de una vida militar en donde te pueden pegar, te pueden hacer t\u00e9cnicas de interrogaci\u00f3n y t\u00fa no muestras ning\u00fan sentimiento.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00abDe hecho, yo creo que hab\u00eda llorado dos veces en mi vida antes de ser actor, entonces yo tra\u00eda un bloqueo emocional, que muchos hombres sufren de eso, a ra\u00edz del machismo y a ra\u00edz de todo esto que no te permiten expresar\u00bb.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<div id=\"Player_Playoncontent\"><iframe id=\"3609147_1675869127006\" title=\"VIDEO: Christian de la Campa iba a entrar al FBI \" width=\"600\" height=\"338\"  allow=\"autoplay; fullscreen\"><\/iframe><script type=\"text\/javascript\" src=\"\/\/widget.playoncenter.com\/newplayer\/ifriendly\/embed.min.js\"><\/script><script type=\"application\/javascript\">(function(){IFRIENDLY_DATA.init({\"idFrm\":\"3609147_1675869127006\",\"type\":\"video\",\"affId\":\"12955\",\"filter\":\"3609147\",\"width\":600,\"height\":338,\"twitter\":\"\",\"volume\":100,\"autoplay\":0,\"hasVideoRelated\":0,\"share_rrss\":1,\"max\":50,\"limit\":25,\"domain\":\"\/\/widget.playoncenter.com\/\",\"viewFriendly\":1});})()<\/script><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Tras estudiar actuaci\u00f3n, Christian logr\u00f3 conectarse con sus emociones.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00abAhora ya lloro con cualquier (cosa). Pongo una pel\u00edcula y lloro, ya no me importa, y me siento mil veces mejor as\u00ed porque disfrutas m\u00e1s la vida con estos rangos emocionales de re\u00edr  fuerte, en vez de estar as\u00ed &#8216;plano&#8217; toda la vida, por eso fue por lo que me qued\u00e9 ac\u00e1\u00bb.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Y aunque no lo crean, a\u00fan le es dif\u00edcil estar frente a las c\u00e1maras.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00abA m\u00ed en lo personal no me llamaba la atenci\u00f3n (la actuaci\u00f3n). De hecho, si te fijas en mis redes, yo subo muy poco contenido porque no me encantan las c\u00e1maras, me cohiben un poco, soy sumamente introvertido. Ahorita pues me pongo un personaje y as\u00ed, pero de repente Christian de la Campa es muy introvertido\u00bb.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Erika Uribe y Lalo Carrasco\/MezcalTV<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Prohibida su reproducci\u00f3n parcial o total. La copia o distribuci\u00f3n no autorizada de este art\u00edculo y su correspondiente imagen infringe los derechos de autor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>08 FEB (MEX).- Christian de la Campa actualmente participa en la telenovela &quot;Cabo&quot; (Univision), al aire en Estados Unidos, pero la oportunidad de ser actor lleg\u00f3 en medio de proyectos con los que buscaba ser parte del FBI, pues estuvo enlistado en la Fuerza A\u00e9rea Norteamericana.<\/p>\n","protected":false},"author":4,"featured_media":6957,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none"},"categories":[1],"tags":[1183,1303],"acf":[],"_links":{"self":[{"href":"https:\/\/mezcalent.com\/news\/wp-json\/wp\/v2\/posts\/6955"}],"collection":[{"href":"https:\/\/mezcalent.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mezcalent.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mezcalent.com\/news\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/mezcalent.com\/news\/wp-json\/wp\/v2\/comments?post=6955"}],"version-history":[{"count":3,"href":"https:\/\/mezcalent.com\/news\/wp-json\/wp\/v2\/posts\/6955\/revisions"}],"predecessor-version":[{"id":6965,"href":"https:\/\/mezcalent.com\/news\/wp-json\/wp\/v2\/posts\/6955\/revisions\/6965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mezcalent.com\/news\/wp-json\/wp\/v2\/media\/6957"}],"wp:attachment":[{"href":"https:\/\/mezcalent.com\/news\/wp-json\/wp\/v2\/media?parent=6955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mezcalent.com\/news\/wp-json\/wp\/v2\/categories?post=6955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mezcalent.com\/news\/wp-json\/wp\/v2\/tags?post=6955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}